{"id":21,"date":"2016-11-21T15:32:48","date_gmt":"2016-11-21T15:32:48","guid":{"rendered":"https:\/\/xml-io.proteusthemes.com\/consulting\/?page_id=21"},"modified":"2017-03-11T22:12:38","modified_gmt":"2017-03-11T22:12:38","slug":"contact-us","status":"publish","type":"page","link":"https:\/\/xml-io.proteusthemes.com\/consultpress\/contact-us\/","title":{"rendered":"Contact Us"},"content":{"rendered":"<div id=\"pl-21\"  class=\"panel-layout\" ><div id=\"pg-21-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-21-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-21-0-0-0\" class=\"so-panel widget widget_pw_contact_profile widget-contact-profile panel-first-child panel-last-child\" data-index=\"0\" >\t\t\t\t<div class=\"card  contact-profile\">\n\t\t\t\t\t<div class=\"card-block  contact-profile__container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"contact-profile__name\">Berlin Office<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-profile__items\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-profile__item\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"contact-profile__icon\">\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa  fa-phone\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"contact-profile__text\">\n\t\t\t\t\t\t\t\t\t\t\t00386 31 567 456\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-profile__item\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"contact-profile__icon\">\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa  fa-envelope\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"contact-profile__text\">\n\t\t\t\t\t\t\t\t\t\t\tberlin@consultpress.com\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-profile__item\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"contact-profile__icon\">\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa  fa-map-marker\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"contact-profile__text\">\n\t\t\t\t\t\t\t\t\t\t\t112 Schritte St. North Berlin\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div><div id=\"pgc-21-0-1\"  class=\"panel-grid-cell\" ><div id=\"panel-21-0-1-0\" class=\"so-panel widget widget_pw_contact_profile widget-contact-profile panel-first-child panel-last-child\" data-index=\"1\" >\t\t\t\t<div class=\"card  contact-profile\">\n\t\t\t\t\t<div class=\"card-block  contact-profile__container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"contact-profile__name\">Vienna Office<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-profile__items\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-profile__item\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"contact-profile__icon\">\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa  fa-phone\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"contact-profile__text\">\n\t\t\t\t\t\t\t\t\t\t\t00386 31 567 457\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-profile__item\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"contact-profile__icon\">\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa  fa-envelope\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"contact-profile__text\">\n\t\t\t\t\t\t\t\t\t\t\tvienna@consultpress.com\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"contact-profile__item\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"contact-profile__icon\">\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa  fa-map-marker\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"contact-profile__text\">\n\t\t\t\t\t\t\t\t\t\t\t8 Linden St. North Vienna\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div><\/div><div id=\"pg-21-1\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-21-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-21-1-0-0\" class=\"so-panel widget widget_sow-google-map panel-first-child panel-last-child\" data-index=\"2\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-google-map so-widget-sow-google-map-default-4cf21e3e39b4-21\"\n\t\t\t\n\t\t>\n<div class=\"sow-google-map-canvas\"\n\tstyle=\"\"\n\tid=\"map-canvas-968313f1f5fe5d167d38c1bb13a0155d\"\n\tdata-options=\"{&quot;address&quot;:&quot;City of london, London&quot;,&quot;zoom&quot;:12,&quot;mobileZoom&quot;:12,&quot;gestureHandling&quot;:&quot;cooperative&quot;,&quot;disableUi&quot;:false,&quot;markerIcon&quot;:&quot;https:\\\/\\\/xml-io.proteusthemes.com\\\/consultpress\\\/wp-content\\\/uploads\\\/sites\\\/44\\\/2016\\\/11\\\/map-marker.png&quot;,&quot;markersDraggable&quot;:false,&quot;markerAtCenter&quot;:true,&quot;markerInfoDisplay&quot;:&quot;click&quot;,&quot;markerInfoMultiple&quot;:true,&quot;markerPositions&quot;:[{&quot;place&quot;:&quot;Kensigton, London&quot;,&quot;info&quot;:&quot;&quot;,&quot;infoSelectedEditor&quot;:&quot;tinymce&quot;,&quot;infoMaxWidth&quot;:&quot;&quot;,&quot;customMarkerIcon&quot;:&quot;&quot;,&quot;customMarkerIconSize&quot;:&quot;&quot;}],&quot;mapName&quot;:&quot;Custom Map&quot;,&quot;mapStyles&quot;:[{&quot;featureType&quot;:&quot;water&quot;,&quot;elementType&quot;:&quot;geometry&quot;,&quot;stylers&quot;:[{&quot;color&quot;:&quot;#e9e9e9&quot;},{&quot;lightness&quot;:17}]},{&quot;featureType&quot;:&quot;landscape&quot;,&quot;elementType&quot;:&quot;geometry&quot;,&quot;stylers&quot;:[{&quot;color&quot;:&quot;#f5f5f5&quot;},{&quot;lightness&quot;:20}]},{&quot;featureType&quot;:&quot;road.highway&quot;,&quot;elementType&quot;:&quot;geometry.fill&quot;,&quot;stylers&quot;:[{&quot;color&quot;:&quot;#ffffff&quot;},{&quot;lightness&quot;:17}]},{&quot;featureType&quot;:&quot;road.highway&quot;,&quot;elementType&quot;:&quot;geometry.stroke&quot;,&quot;stylers&quot;:[{&quot;color&quot;:&quot;#ffffff&quot;},{&quot;lightness&quot;:29},{&quot;weight&quot;:0.2}]},{&quot;featureType&quot;:&quot;road.arterial&quot;,&quot;elementType&quot;:&quot;geometry&quot;,&quot;stylers&quot;:[{&quot;color&quot;:&quot;#ffffff&quot;},{&quot;lightness&quot;:18}]},{&quot;featureType&quot;:&quot;road.local&quot;,&quot;elementType&quot;:&quot;geometry&quot;,&quot;stylers&quot;:[{&quot;color&quot;:&quot;#ffffff&quot;},{&quot;lightness&quot;:16}]},{&quot;featureType&quot;:&quot;poi&quot;,&quot;elementType&quot;:&quot;geometry&quot;,&quot;stylers&quot;:[{&quot;color&quot;:&quot;#f5f5f5&quot;},{&quot;lightness&quot;:21}]},{&quot;featureType&quot;:&quot;poi.park&quot;,&quot;elementType&quot;:&quot;geometry&quot;,&quot;stylers&quot;:[{&quot;color&quot;:&quot;#dedede&quot;},{&quot;lightness&quot;:21}]},{&quot;elementType&quot;:&quot;labels.text.stroke&quot;,&quot;stylers&quot;:[{&quot;visibility&quot;:&quot;on&quot;},{&quot;color&quot;:&quot;#ffffff&quot;},{&quot;lightness&quot;:16}]},{&quot;elementType&quot;:&quot;labels.text.fill&quot;,&quot;stylers&quot;:[{&quot;saturation&quot;:36},{&quot;color&quot;:&quot;#333333&quot;},{&quot;lightness&quot;:40}]},{&quot;elementType&quot;:&quot;labels.icon&quot;,&quot;stylers&quot;:[{&quot;visibility&quot;:&quot;off&quot;}]},{&quot;featureType&quot;:&quot;transit&quot;,&quot;elementType&quot;:&quot;geometry&quot;,&quot;stylers&quot;:[{&quot;color&quot;:&quot;#f2f2f2&quot;},{&quot;lightness&quot;:19}]},{&quot;featureType&quot;:&quot;administrative&quot;,&quot;elementType&quot;:&quot;geometry.fill&quot;,&quot;stylers&quot;:[{&quot;color&quot;:&quot;#fefefe&quot;},{&quot;lightness&quot;:20}]},{&quot;featureType&quot;:&quot;administrative&quot;,&quot;elementType&quot;:&quot;geometry.stroke&quot;,&quot;stylers&quot;:[{&quot;color&quot;:&quot;#fefefe&quot;},{&quot;lightness&quot;:17},{&quot;weight&quot;:1.2}]}],&quot;directions&quot;:&quot;&quot;,&quot;apiKey&quot;:&quot;&quot;,&quot;breakpoint&quot;:&quot;780&quot;}\"\n\tdata-fallback-image=\"{&quot;img&quot;:&quot;&quot;}\"><\/div>\n<\/div><\/div><\/div><div id=\"pgc-21-1-1\"  class=\"panel-grid-cell\" ><div id=\"panel-21-1-1-0\" class=\"so-panel widget widget_pw_opening_time opening-time panel-first-child panel-last-child\" data-index=\"3\" >\n\t<div class=\"time-table\">\n\n\t\t\t\t\t<h2 class=\"h4  widget-title\">Opening Times<\/h2>\n\t\t\n\t\t<div class=\"inner-bg\">\n\t\t\t\t\t\t\t<dl class=\"week-day \">\n\t\t\t\t\t<dt>Mon<\/dt>\n\t\t\t\t\t<dd class=\"week-day__line\"><\/dd>\n\t\t\t\t\t<dd>8:00 - 16:00<\/dd>\n\t\t\t\t<\/dl>\n\t\t\t\t\t\t\t<dl class=\"week-day  light-bg\">\n\t\t\t\t\t<dt>Tue<\/dt>\n\t\t\t\t\t<dd class=\"week-day__line\"><\/dd>\n\t\t\t\t\t<dd>8:00 - 16:00<\/dd>\n\t\t\t\t<\/dl>\n\t\t\t\t\t\t\t<dl class=\"week-day  today\">\n\t\t\t\t\t<dt>Wed<\/dt>\n\t\t\t\t\t<dd class=\"week-day__line\"><\/dd>\n\t\t\t\t\t<dd>8:00 - 16:00<\/dd>\n\t\t\t\t<\/dl>\n\t\t\t\t\t\t\t<dl class=\"week-day  light-bg\">\n\t\t\t\t\t<dt>Thu<\/dt>\n\t\t\t\t\t<dd class=\"week-day__line\"><\/dd>\n\t\t\t\t\t<dd>8:00 - 16:00<\/dd>\n\t\t\t\t<\/dl>\n\t\t\t\t\t\t\t<dl class=\"week-day \">\n\t\t\t\t\t<dt>Fri<\/dt>\n\t\t\t\t\t<dd class=\"week-day__line\"><\/dd>\n\t\t\t\t\t<dd>8:00 - 16:00<\/dd>\n\t\t\t\t<\/dl>\n\t\t\t\t\t\t\t<dl class=\"week-day  light-bg closed\">\n\t\t\t\t\t<dt>Sat<\/dt>\n\t\t\t\t\t<dd class=\"week-day__line\"><\/dd>\n\t\t\t\t\t<dd>Closed<\/dd>\n\t\t\t\t<\/dl>\n\t\t\t\t\t\t\t<dl class=\"week-day  closed\">\n\t\t\t\t\t<dt>Sun<\/dt>\n\t\t\t\t\t<dd class=\"week-day__line\"><\/dd>\n\t\t\t\t\t<dd>Closed<\/dd>\n\t\t\t\t<\/dl>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"additional-info\">Lunch break 8:00 - 8:30<\/div>\n\t\t\n\t<\/div>\n\n<\/div><\/div><\/div><div id=\"pg-21-2\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch panel-row-style panel-row-style-for-21-2\" data-stretch-type=\"full\" ><div id=\"pgc-21-2-0\"  class=\"panel-grid-cell\" ><div id=\"panel-21-2-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"4\" ><div class=\"contact-light panel-widget-style panel-widget-style-for-21-2-0-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h2>Message Us<\/h2>\n<p>Our experts and industry consultants work with a wide variety of clients, across different industries which includes change oriented CEOs.<\/p>\n<p>This form is using Contact Form 7 plugin. There is an alternative: <a href=\"https:\/\/xml-io.proteusthemes.com\/consultpress\/contact-us-caldera-forms\/\">Caldera Form<\/a>\u00a0(officially supported plugin).<\/p>\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f192-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"192\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/consultpress\/wp-json\/wp\/v2\/pages\/21#wpcf7-f192-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"192\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.4\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f192-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"row\">\n\t<div class=\"col-xs-12  col-lg-6\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-control\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"First Name*\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-xs-12  col-lg-6\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email form-control\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-mail*\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-xs-12  col-lg-6\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text form-control\" aria-invalid=\"false\" placeholder=\"Subject\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-xs-12  col-lg-6\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-text wpcf7-validates-as-tel form-control\" aria-invalid=\"false\" placeholder=\"Phone Number\" value=\"\" type=\"tel\" name=\"your-phone\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-xs-12\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea form-control\" aria-invalid=\"false\" placeholder=\"Message\" name=\"your-message\"><\/textarea><\/span><input class=\"wpcf7-form-control wpcf7-submit has-spinner btn btn-secondary\" type=\"submit\" value=\"Request a call\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Berlin Office 00386 31 567 456 berlin@consultpress.com 112 Schritte St. North Berlin Vienna Office 00386 31 567 457 vienna@consultpress.com 8 Linden St. North Vienna Opening Times Mon 8:00 &#8211; 16:00 Tue 8:00 &#8211; 16:00 Wed 8:00 &#8211; 16:00 Thu 8:00 &#8211; 16:00 Fri 8:00 &#8211; 16:00 Sat Closed Sun Closed Lunch break 8:00 &#8211; 8:30 &hellip;<\/p>\n","protected":false},"author":8,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":{"0":"post-21","1":"page","2":"type-page","3":"status-publish","5":"clearfix","6":"article"},"acf":[],"_links":{"self":[{"href":"https:\/\/xml-io.proteusthemes.com\/consultpress\/wp-json\/wp\/v2\/pages\/21","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xml-io.proteusthemes.com\/consultpress\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/xml-io.proteusthemes.com\/consultpress\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/xml-io.proteusthemes.com\/consultpress\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/xml-io.proteusthemes.com\/consultpress\/wp-json\/wp\/v2\/comments?post=21"}],"version-history":[{"count":6,"href":"https:\/\/xml-io.proteusthemes.com\/consultpress\/wp-json\/wp\/v2\/pages\/21\/revisions"}],"predecessor-version":[{"id":805,"href":"https:\/\/xml-io.proteusthemes.com\/consultpress\/wp-json\/wp\/v2\/pages\/21\/revisions\/805"}],"wp:attachment":[{"href":"https:\/\/xml-io.proteusthemes.com\/consultpress\/wp-json\/wp\/v2\/media?parent=21"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}